{"id":139529,"date":"2025-11-18T19:39:33","date_gmt":"2025-11-18T19:39:33","guid":{"rendered":"https:\/\/www.pshhc.org\/?page_id=139529"},"modified":"2026-03-30T22:50:19","modified_gmt":"2026-03-30T22:50:19","slug":"bga","status":"publish","type":"page","link":"https:\/\/www.pshhc.org\/es\/bga\/","title":{"rendered":"Apartamentos Buellton Garden"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid inner-banner vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  bg-image\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/12\/Building-B.1-scaled.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Edificio B.1\" srcset=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/12\/Building-B.1-scaled.png 2560w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/12\/Building-B.1-300x169.png 300w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/12\/Building-B.1-1024x576.png 1024w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/12\/Building-B.1-768x432.png 768w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/12\/Building-B.1-1536x864.png 1536w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/12\/Building-B.1-2048x1152.png 2048w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/12\/Building-B.1-18x10.png 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid inner-housing-section vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element inner-housing-section\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\">Apartamentos Buellton Garden<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid rental-housing-section vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ubtn-ctn-center\"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-center ubtn-custom\" href=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2026\/01\/BGA-Lease-Up-Instruction-Sheet-Pre-App.pdf\" target=\"_blank\" rel=\"noopener\" ><button type=\"button\" id=\"ubtn-3816\"  class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-custom ubtn-no-hover-bg  none  ubtn-center   tooltip-6a04aee7c61af\"  data-hover=\"#9B0002\" data-border-color=\"\" data-bg=\"#9B0002\" data-hover-bg=\"#FFFFFF\" data-border-hover=\"\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-3816'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;width:450px;min-height:55px;padding:px px;border:none;background: #9B0002;color: #FFFFFF;\"><span class=\"ubtn-hover\" style=\"background-color:#FFFFFF\"><\/span><span class=\"ubtn-data ubtn-text\" >Descargar presolicitud e instrucciones<\/span><\/button><\/a><\/div>\n\t<div class=\"wpb_text_column wpb_content_element container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Opciones para presentar una pre-solicitud:<\/p>\n<ul>\n<li style=\"text-align: left;\">Por correo electr\u00f3nico a <a href=\"mailto:BGA@pshhc.org\">BGA@pshhc.org<\/a><\/li>\n<li style=\"text-align: left;\">V\u00eda fax al (805) 693-3003<\/li>\n<li style=\"text-align: left;\">V\u00eda correo o en persona a: <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"> Apartamentos Buellton Garden c\/o College Park Apartments, 648 North G St, Lompoc, CA 93436<\/span>\n<ul>\n<li style=\"text-align: left;\"><strong><em>Nota: Los Apartamentos Buellton Garden a\u00fan est\u00e1n en construcci\u00f3n. No se aceptan solicitudes previas en el sitio.<\/em><\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Las solicitudes previas se a\u00f1aden a la lista de espera en el orden en que se reciben.<\/p>\n<p>Si est\u00e1 discapacitado, desea solicitar una adaptaci\u00f3n razonable o si tiene dificultades para entender ingl\u00e9s, comun\u00edquese con nuestro equipo en <a href=\"mailto:bga@pshhc.org\">BGA@pshhc.org<\/a> o al (805) 693-3004. Nos aseguraremos de que reciba un acceso significativo en funci\u00f3n de sus necesidades individuales.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid rental-housing-section container vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Las preinscripciones estar\u00e1n disponibles en esta p\u00e1gina web a partir del martes 13 de enero a las 9:00. <strong><em>Aviso: El complejo de apartamentos Buellton Garden a\u00fan est\u00e1 en construcci\u00f3n. No se aceptan solicitudes previas en el sitio web.<\/em><\/strong><\/p>\n<p>Las solicitudes previas recibidas antes de las 17:00 del 3 de febrero participar\u00e1n en un sorteo aleatorio el 10 de febrero para determinar el orden de tramitaci\u00f3n. Las solicitudes previas recibidas despu\u00e9s del 3 de febrero se a\u00f1adir\u00e1n a la lista de espera por orden de llegada.<\/p>\n<p>Si est\u00e1 discapacitado, desea solicitar una adaptaci\u00f3n razonable o si tiene dificultades para entender ingl\u00e9s, comun\u00edquese con nuestro equipo en <a href=\"mailto:bga@pshhc.org\">BGA@pshhc.org<\/a> o al (805) 693-3004. Nos aseguraremos de que reciba un acceso significativo en funci\u00f3n de sus necesidades individuales.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid rental-housing-section vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 25px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_tta-container\" data-vc-action=\"collapseAll\"><div class=\"vc_general vc_tta vc_tta-accordion vc_tta-color-grey vc_tta-style-classic vc_tta-shape-rounded vc_tta-o-shape-group vc_tta-controls-align-default vc_tta-o-all-clickable  container\"><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel\" id=\"1763678409515-22152b6f-b50b\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678409515-22152b6f-b50b\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfQui\u00e9nes pueden residir en los apartamentos Buellton Garden?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>El complejo de apartamentos Buellton Garden consta de 89 viviendas multifamiliares asequibles para familias con ingresos iguales o inferiores al 50% del ingreso medio del \u00e1rea (AMI). Consulte los &quot;L\u00edmites m\u00e1ximos de ingresos&quot; a continuaci\u00f3n para comprobar si cumple los requisitos.<\/p>\n<p>Tambi\u00e9n se reservar\u00e1n 24 unidades para hogares de trabajadores agr\u00edcolas con ingresos entre 30 y 501 TP3T del AMI. Se define como &quot;trabajador agr\u00edcola&quot; a toda persona que obtiene una parte sustancial de sus ingresos del trabajo agr\u00edcola. Los trabajadores agr\u00edcolas jubilados tambi\u00e9n pueden optar a estas unidades. Entre los empleos que cumplen los requisitos se incluyen, entre otros:<\/p>\n<ul>\n<li>Cultivo del suelo<\/li>\n<li>Producci\u00f3n, cultivo y cosecha de cualquier producto agr\u00edcola u hort\u00edcola.<\/li>\n<li>Cr\u00eda de ganado, abejas, animales de piel o aves de corral.<\/li>\n<li>Venta de productos l\u00e1cteos<\/li>\n<li>Operaciones forestales y madereras<\/li>\n<li>Entrega y preparaci\u00f3n de productos para el mercado o almacenamiento<\/li>\n<\/ul>\n<p>Si no est\u00e1 seguro de si su puesto califica, env\u00edenos un correo electr\u00f3nico a <a href=\"mailto:BGA@pshhc.org\">BGA@pshhc.org<\/a>.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678409613-abe80046-1187\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678409613-abe80046-1187\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfCu\u00e1les son los l\u00edmites de ingresos?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Al momento de solicitar, el ingreso bruto anual total de su hogar no debe exceder los l\u00edmites establecidos a continuaci\u00f3n. Cada unidad tiene diferentes requisitos de elegibilidad de AMI, que van de 30 a 50%, seg\u00fan su financiamiento. Al recibir su pre-solicitud, verificaremos su elegibilidad y le asignaremos una unidad disponible que cumpla con sus requisitos.<\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-139637 size-full\" src=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Buellton-e1764104981333.png\" alt=\"\" width=\"800\" height=\"265\" srcset=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Buellton-e1764104981333.png 800w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Buellton-e1764104981333-300x99.png 300w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Buellton-e1764104981333-768x254.png 768w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Buellton-e1764104981333-18x6.png 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Estos l\u00edmites de ingresos entrar\u00e1n en vigor el 1 de abril de 2025. <\/em><em>Son determinadas por el Departamento de Vivienda y Desarrollo Urbano de los Estados Unidos y cambian anualmente.<\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678409707-0f7bbfc9-12d5\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678409707-0f7bbfc9-12d5\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfC\u00f3mo puedo aplicar?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>A partir del 13 de enero a las 9:00, podr\u00e1 enviar la preinscripci\u00f3n de varias maneras:<\/p>\n<ul>\n<li>Por correo electr\u00f3nico a <a href=\"mailto:BGA@pshhc.org\">BGA@pshhc.org<\/a><\/li>\n<li>V\u00eda fax al (805) 693-3003<\/li>\n<li>Por correo o en persona a: Buellton Garden Apartments c\/o College Park Apartments, 648 North G St, Lompoc, CA 93436\n<ul>\n<li><strong><em>Nota: Los Apartamentos Buellton Garden a\u00fan est\u00e1n en construcci\u00f3n. No se aceptan solicitudes previas en el sitio.<\/em><\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678409794-4e597867-e76b\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678409794-4e597867-e76b\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfCu\u00e1l es la l\u00ednea de tiempo?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>A continuaci\u00f3n se indican algunas fechas clave:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>13 de enero a las 9:00 a. m.:<\/strong> Las solicitudes previas estar\u00e1n disponibles en esta p\u00e1gina web.<\/li>\n<li><strong>10 de febrero a las 17 h:<\/strong> Fecha l\u00edmite para presentar solicitudes preliminares<\/li>\n<li><b>17 de febrero: <\/b>ocurre la loter\u00eda<\/li>\n<li><span style=\"font-family: FuturaStd-Heavy;\"><b>20 de febrero: <\/b><\/span>cartas de notificaci\u00f3n de loter\u00eda enviadas por correo<\/li>\n<li><strong>20 de marzo<\/strong>Cartas de entrevista enviadas por correo<\/li>\n<li><strong>30 de marzo:<\/strong> Comienzan las entrevistas<\/li>\n<li><strong>1 de julio:<\/strong> mudanzas (<em>tentativo<\/em>)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678409881-6162c9bb-779e\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678409881-6162c9bb-779e\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfPuedo obtener ayuda para completar la preinscripci\u00f3n?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u00a1Estar\u00edamos encantados de ayudarle! Nuestro equipo est\u00e1 disponible de lunes a viernes de 8 am a 5 pm. Puedes comunicarte con <a href=\"mailto:BGA@pshhc.org\">BGA@pshhc.org<\/a> o (805) 693-3004 con sus preguntas o para programar una cita para recibir asistencia.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678409969-de2db83f-1ab0\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678409969-de2db83f-1ab0\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfQu\u00e9 informaci\u00f3n se necesita para la pre-solicitud?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>La solicitud previa solicitar\u00e1:<\/p>\n<ul>\n<li>Datos de contacto de todos los miembros adultos del hogar<\/li>\n<li>Informaci\u00f3n general sobre todas las personas que vivir\u00e1n con usted en la unidad<\/li>\n<li>Resumen de ingresos y activos<\/li>\n<li>Preferencias de planos de planta\/caracter\u00edsticas de accesibilidad<\/li>\n<\/ul>\n<p>No se requiere documentaci\u00f3n para la solicitud previa, pero ser\u00e1 necesaria una vez que haya sido aprobado para el procesamiento posterior.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410042-33b0df51-9222\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410042-33b0df51-9222\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfCu\u00e1l es el criterio de selecci\u00f3n?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Para recibir una copia de nuestro Plan de selecci\u00f3n de inquilinos, env\u00edenos un correo electr\u00f3nico a <a href=\"mailto:BGA@pshhc.org\">BGA@pshhc.org<\/a>.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410129-81c7c174-fe17\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410129-81c7c174-fe17\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfSe acepta la Secci\u00f3n 8?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u00a1S\u00ed! Se acepta la secci\u00f3n 8. Sin embargo, PSHH no proporciona vales de la Secci\u00f3n 8. Si actualmente no tiene un cup\u00f3n, visite el <a href=\"https:\/\/www.hasbarco.org\/\">Autoridad de Vivienda del Condado de Santa B\u00e1rbara<\/a>\u00a0para obtener m\u00e1s informaci\u00f3n e inscribirse.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410223-7a224af5-225e\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410223-7a224af5-225e\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfQu\u00e9 planos de planta est\u00e1n disponibles?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>De las 89 unidades en Buellton Garden Apartments:<\/p>\n<ul>\n<li>30 unidades son <strong>1 dormitorio, 1 ba\u00f1o (<\/strong>595 pies cuadrados)<\/li>\n<li>37 unidades son <strong>2 dormitorios, 1 ba\u00f1o<\/strong> (777 pies cuadrados)<\/li>\n<li>22 unidades son <strong>3 dormitorios, 2 ba\u00f1os<\/strong> (1027 pies cuadrados)<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2026\/02\/FloorPlans-BG.pdf\" target=\"_blank\" rel=\"noopener\">Vea nuestros planos de planta completos<\/a> Para m\u00e1s detalles.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410321-9126e0d2-3cb0\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410321-9126e0d2-3cb0\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfD\u00f3nde est\u00e1 localizada la propiedad?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Los apartamentos Buellton Garden est\u00e1n ubicados en el n\u00famero 10 de McMurray Road, en la ciudad de Buellton. Tenga en cuenta que a\u00fan se trata de una obra en construcci\u00f3n, por lo que le rogamos que no entre en la propiedad.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410421-8da804e6-2474\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410421-8da804e6-2474\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfCu\u00e1les son las caracter\u00edsticas de la propiedad?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Todas las unidades estar\u00e1n equipadas con lavavajillas, refrigerador, estufa, cortinas y pisos de vinilo nuevos. Tambi\u00e9n habr\u00e1 unidades accesibles para personas con movilidad reducida y con necesidades especiales. El complejo cuenta con dos edificios de tres pisos. Los residentes tienen acceso a estacionamiento descubierto, lavander\u00eda, centro comunitario, centro de aprendizaje, cancha de baloncesto (media cancha) y \u00e1rea de juegos infantiles. Est\u00e1 prohibido fumar en la propiedad.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410528-5f316755-12d0\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410528-5f316755-12d0\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfSe admiten mascotas en los apartamentos Buellton Garden?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u00a1S\u00ed! Se permiten mascotas. Por favor h\u00e1ganoslo saber al momento de presentar la solicitud. Hay un dep\u00f3sito por mascota de $150.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410679-bb1f8e44-2590\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410679-bb1f8e44-2590\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfQu\u00e9 servicios se ofrecen?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Los servicios gratuitos en el lugar incluyen administraci\u00f3n de la propiedad, apoyo extraescolar para estudiantes de K-8 y gesti\u00f3n de casos por parte de trabajadores sociales con licencia.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410820-249e835d-7690\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410820-249e835d-7690\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfQui\u00e9n paga los servicios p\u00fablicos?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Los residentes pagar\u00e1n su propio consumo de electricidad. PSHH se hace cargo del agua, el alcantarillado y la basura. Cada unidad recibe una asignaci\u00f3n mensual para servicios p\u00fablicos.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678410930-873d7dc4-2d13\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678410930-873d7dc4-2d13\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfC\u00f3mo se calculan las rentas?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>El alquiler se basa en el n\u00famero de habitaciones y el tama\u00f1o de la vivienda. Los ingresos familiares deben ser al menos 2,5 veces el alquiler mensual, a menos que el solicitante reciba un subsidio de alquiler para inquilinos (por ejemplo, la Secci\u00f3n 8). Los l\u00edmites m\u00e1ximos de alquiler actuales son:<\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-140585 size-full\" src=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2026\/03\/Buellton-4-e1774549204397.png\" alt=\"\" width=\"800\" height=\"248\" srcset=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2026\/03\/Buellton-4-e1774549204397.png 800w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2026\/03\/Buellton-4-e1774549204397-300x93.png 300w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2026\/03\/Buellton-4-e1774549204397-768x238.png 768w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2026\/03\/Buellton-4-e1774549204397-18x6.png 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Estos alquileres entran en vigor a partir del 1 de abril de 2025. Son determinados por el Departamento de Vivienda y Desarrollo Urbano y est\u00e1n sujetos a cambios.<\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678411029-7d47b87f-d919\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678411029-7d47b87f-d919\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfHay dep\u00f3sitos de seguridad?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Se requieren dep\u00f3sitos de seguridad, pero hay alternativas disponibles si esto generara dificultades financieras.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1763678411145-171db923-2107\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1763678411145-171db923-2107\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u00bfCu\u00e1ndo puedo mudarme?<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>La propiedad a\u00fan est\u00e1 en construcci\u00f3n, pero actualmente se estima que estar\u00e1 abierta para ocupaci\u00f3n en junio de 2026. Nos mantendremos en contacto con los nuevos residentes si hay cambios en este cronograma.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><em>People&#039;s Self-Help Housing es un proveedor y empleador que ofrece igualdad de oportunidades. TDD # 1-800-735-2922 o 711<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-134616 aligncenter\" src=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2024\/03\/Housing.jpg\" alt=\"\" width=\"97\" height=\"53\" srcset=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2024\/03\/Housing.jpg 97w, https:\/\/www.pshhc.org\/wp-content\/uploads\/2024\/03\/Housing-18x10.jpg 18w\" sizes=\"auto, (max-width: 97px) 100vw, 97px\" \/><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Apartamentos Buellton Garden. Descargue la presolicitud e instrucciones. Opciones para enviar la presolicitud: Por correo electr\u00f3nico a BGA@pshhc.org. Por fax al (805) 693-3003. Por correo postal o en persona a: Apartamentos Buellton Garden, c\/o College Park Apartments, 648 North G St, Lompoc, CA 93436. Nota: Los Apartamentos Buellton Garden a\u00fan est\u00e1n en construcci\u00f3n. No se aceptan presolicitudes.  <a class=\"excerpt-read-more\" href=\"https:\/\/www.pshhc.org\/es\/bga\/\" title=\"Leer Buellton Garden Apartments\">Leer m\u00e1s &quot;<\/a>","protected":false},"author":1113,"featured_media":139650,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-wide.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-139529","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Buellton Garden Apartments - People&#039;s Self-Help Housing<\/title>\n<meta name=\"description\" content=\"Buellton Garden Apartments Download Pre-Application &amp; Instructions Options to submit a pre-application: Via email to BGA@pshhc.org Via fax to (805) 693-3003 Via mail or in-person to: Buellton Garden Apartments c\/o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pshhc.org\/es\/bga\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buellton Garden Apartments - People&#039;s Self-Help Housing\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pshhc.org\/es\/bga\/\" \/>\n<meta property=\"og:site_name\" content=\"People&#039;s Self-Help Housing\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T22:50:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Rendering-1-e1764104921368.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"468\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pshhc.org\\\/bga\\\/\",\"url\":\"https:\\\/\\\/www.pshhc.org\\\/bga\\\/\",\"name\":\"Buellton Garden Apartments - People&#039;s Self-Help Housing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pshhc.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pshhc.org\\\/bga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pshhc.org\\\/bga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pshhc.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Rendering-1-e1764104921368.jpg\",\"datePublished\":\"2025-11-18T19:39:33+00:00\",\"dateModified\":\"2026-03-30T22:50:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pshhc.org\\\/bga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pshhc.org\\\/bga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pshhc.org\\\/bga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pshhc.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Rendering-1-e1764104921368.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pshhc.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Rendering-1-e1764104921368.jpg\",\"width\":1400,\"height\":468},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pshhc.org\\\/bga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pshhc.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buellton Garden Apartments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pshhc.org\\\/#website\",\"url\":\"https:\\\/\\\/www.pshhc.org\\\/\",\"name\":\"People&#039;s Self-Help Housing\",\"description\":\"People&#039;s Self-Help Housing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pshhc.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apartamentos Buellton Garden - Viviendas de autoayuda para personas","description":"Apartamentos Buellton Garden Descargar solicitud previa e instrucciones Opciones para enviar una solicitud previa: Por correo electr\u00f3nico a BGA@pshhc.org Por fax al (805) 693-3003 Por correo postal o en persona a: Apartamentos Buellton Garden c\/o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pshhc.org\/es\/bga\/","og_locale":"es_MX","og_type":"article","og_title":"Buellton Garden Apartments - People&#039;s Self-Help Housing","og_url":"https:\/\/www.pshhc.org\/es\/bga\/","og_site_name":"People&#039;s Self-Help Housing","article_modified_time":"2026-03-30T22:50:19+00:00","og_image":[{"width":1400,"height":468,"url":"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Rendering-1-e1764104921368.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pshhc.org\/bga\/","url":"https:\/\/www.pshhc.org\/bga\/","name":"Apartamentos Buellton Garden - Viviendas de autoayuda para personas","isPartOf":{"@id":"https:\/\/www.pshhc.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pshhc.org\/bga\/#primaryimage"},"image":{"@id":"https:\/\/www.pshhc.org\/bga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Rendering-1-e1764104921368.jpg","datePublished":"2025-11-18T19:39:33+00:00","dateModified":"2026-03-30T22:50:19+00:00","breadcrumb":{"@id":"https:\/\/www.pshhc.org\/bga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pshhc.org\/bga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pshhc.org\/bga\/#primaryimage","url":"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Rendering-1-e1764104921368.jpg","contentUrl":"https:\/\/www.pshhc.org\/wp-content\/uploads\/2025\/11\/Rendering-1-e1764104921368.jpg","width":1400,"height":468},{"@type":"BreadcrumbList","@id":"https:\/\/www.pshhc.org\/bga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pshhc.org\/"},{"@type":"ListItem","position":2,"name":"Buellton Garden Apartments"}]},{"@type":"WebSite","@id":"https:\/\/www.pshhc.org\/#website","url":"https:\/\/www.pshhc.org\/","name":"Vivienda de autoayuda de People &amp; #039; s","description":"Vivienda de autoayuda de People &amp; #039; s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pshhc.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/pages\/139529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/users\/1113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/comments?post=139529"}],"version-history":[{"count":26,"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/pages\/139529\/revisions"}],"predecessor-version":[{"id":140620,"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/pages\/139529\/revisions\/140620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/media\/139650"}],"wp:attachment":[{"href":"https:\/\/www.pshhc.org\/es\/wp-json\/wp\/v2\/media?parent=139529"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}